{"id":1501,"date":"2024-11-22T14:14:13","date_gmt":"2024-11-22T14:14:13","guid":{"rendered":"https:\/\/josam.se\/?page_id=1501"},"modified":"2025-01-29T21:24:55","modified_gmt":"2025-01-29T21:24:55","slug":"sales","status":"publish","type":"page","link":"https:\/\/josam.se\/sv\/sales\/","title":{"rendered":"F\u00f6rs\u00e4ljning"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">This is the content of the Sales Page<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This is the content of the Sales Page<\/p>\n","protected":false},"author":1,"featured_media":1502,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/sales.php","meta":{"footnotes":""},"class_list":["post-1501","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00f6rs\u00e4ljning - JOSAM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/josam.se\/sv\/sales\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00f6rs\u00e4ljning - JOSAM\" \/>\n<meta property=\"og:description\" content=\"This is the content of the Sales Page\" \/>\n<meta property=\"og:url\" content=\"https:\/\/josam.se\/sv\/sales\/\" \/>\n<meta property=\"og:site_name\" content=\"JOSAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/josamsweden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-29T21:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/josam.se\/wp-content\/uploads\/contact-hero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/\",\"url\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/\",\"name\":\"F\u00f6rs\u00e4ljning - JOSAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/contact-hero.jpg\",\"datePublished\":\"2024-11-22T14:14:13+00:00\",\"dateModified\":\"2025-01-29T21:24:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/contact-hero.jpg\",\"contentUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/contact-hero.jpg\",\"width\":1920,\"height\":720,\"caption\":\"JOSAM Service Center\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/sales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/josam.se\\\/sv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00f6rs\u00e4ljning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/#website\",\"url\":\"https:\\\/\\\/josam.se\\\/sv\\\/\",\"name\":\"JOSAM\",\"description\":\"Heavy Duty\",\"publisher\":{\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/josam.se\\\/sv\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/#organization\",\"name\":\"JOSAM\",\"url\":\"https:\\\/\\\/josam.se\\\/sv\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/JOSAM-NEW-simple-black-cropped.svg\",\"contentUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/JOSAM-NEW-simple-black-cropped.svg\",\"width\":792,\"height\":153,\"caption\":\"JOSAM\"},\"image\":{\"@id\":\"https:\\\/\\\/josam.se\\\/sv\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/josamsweden\",\"https:\\\/\\\/www.instagram.com\\\/josamequipment\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@josamsweden\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/josam\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00f6rs\u00e4ljning - JOSAM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/josam.se\/sv\/sales\/","og_locale":"sv_SE","og_type":"article","og_title":"F\u00f6rs\u00e4ljning - JOSAM","og_description":"This is the content of the Sales Page","og_url":"https:\/\/josam.se\/sv\/sales\/","og_site_name":"JOSAM","article_publisher":"https:\/\/www.facebook.com\/josamsweden","article_modified_time":"2025-01-29T21:24:55+00:00","og_image":[{"width":1920,"height":720,"url":"http:\/\/josam.se\/wp-content\/uploads\/contact-hero.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Ber\u00e4knad l\u00e4stid":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/josam.se\/sv\/sales\/","url":"https:\/\/josam.se\/sv\/sales\/","name":"F\u00f6rs\u00e4ljning - JOSAM","isPartOf":{"@id":"https:\/\/josam.se\/sv\/#website"},"primaryImageOfPage":{"@id":"https:\/\/josam.se\/sv\/sales\/#primaryimage"},"image":{"@id":"https:\/\/josam.se\/sv\/sales\/#primaryimage"},"thumbnailUrl":"https:\/\/josam.se\/wp-content\/uploads\/contact-hero.jpg","datePublished":"2024-11-22T14:14:13+00:00","dateModified":"2025-01-29T21:24:55+00:00","breadcrumb":{"@id":"https:\/\/josam.se\/sv\/sales\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/josam.se\/sv\/sales\/"]}]},{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/josam.se\/sv\/sales\/#primaryimage","url":"https:\/\/josam.se\/wp-content\/uploads\/contact-hero.jpg","contentUrl":"https:\/\/josam.se\/wp-content\/uploads\/contact-hero.jpg","width":1920,"height":720,"caption":"JOSAM Service Center"},{"@type":"BreadcrumbList","@id":"https:\/\/josam.se\/sv\/sales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/josam.se\/sv\/"},{"@type":"ListItem","position":2,"name":"F\u00f6rs\u00e4ljning"}]},{"@type":"WebSite","@id":"https:\/\/josam.se\/sv\/#website","url":"https:\/\/josam.se\/sv\/","name":"JOSAM","description":"Heavy Duty","publisher":{"@id":"https:\/\/josam.se\/sv\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/josam.se\/sv\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Organization","@id":"https:\/\/josam.se\/sv\/#organization","name":"JOSAM","url":"https:\/\/josam.se\/sv\/","logo":{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/josam.se\/sv\/#\/schema\/logo\/image\/","url":"https:\/\/josam.se\/wp-content\/uploads\/JOSAM-NEW-simple-black-cropped.svg","contentUrl":"https:\/\/josam.se\/wp-content\/uploads\/JOSAM-NEW-simple-black-cropped.svg","width":792,"height":153,"caption":"JOSAM"},"image":{"@id":"https:\/\/josam.se\/sv\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/josamsweden","https:\/\/www.instagram.com\/josamequipment\/","https:\/\/www.youtube.com\/@josamsweden","https:\/\/www.linkedin.com\/company\/josam"]}]}},"_links":{"self":[{"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/pages\/1501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/comments?post=1501"}],"version-history":[{"count":2,"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/pages\/1501\/revisions"}],"predecessor-version":[{"id":2258,"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/pages\/1501\/revisions\/2258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/media\/1502"}],"wp:attachment":[{"href":"https:\/\/josam.se\/sv\/wp-json\/wp\/v2\/media?parent=1501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}