{"id":2051,"date":"2024-10-03T20:28:50","date_gmt":"2024-10-03T20:28:50","guid":{"rendered":"https:\/\/josam.se\/product\/induction-heating\/jh400\/"},"modified":"2026-06-04T13:47:02","modified_gmt":"2026-06-04T13:47:02","slug":"jh400","status":"publish","type":"product","link":"https:\/\/josam.se\/it\/prodotti\/jh400\/","title":{"rendered":"JH400"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Precisione ed efficienza per le attivit\u00e0 quotidiane<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il riscaldatore a induzione JH400 \u00e8 adatto per le attivit\u00e0 di riparazione leggera, come il raddrizzamento di lamiere e l&#8217;allentamento di piccole parti della macchina come perni, anelli di serraggio e dadi. Il design compatto e il funzionamento intuitivo lo rendono uno strumento essenziale per qualsiasi officina. JH400 \u00e8 la soluzione ideale per lavori di riparazione leggera efficienti e precisi.\u00a0 Offre una facilit\u00e0 d&#8217;uso e una durata senza pari in ambienti difficili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Precisione ed efficienza per le attivit\u00e0 quotidiane Il riscaldatore a induzione JH400 \u00e8 adatto per le attivit\u00e0 di riparazione leggera, come il raddrizzamento di lamiere e l&#8217;allentamento di piccole parti della macchina come perni, anelli di serraggio e dadi. Il design compatto e il funzionamento intuitivo lo rendono uno strumento essenziale per qualsiasi officina. JH400 [&hellip;]<\/p>\n","protected":false},"featured_media":8883,"parent":1657,"menu_order":2,"template":"page-templates\/product-single.php","format":"standard","meta":[],"class_list":["post-2051","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riscaldatore a induzione per lavori leggeri JH400 | JOSAM IT<\/title>\n<meta name=\"description\" content=\"JH400 \u00e8 ideale per raddrizzare lamiere e allentare parti piccole come dadi e perni. Utilizzato per lo pi\u00f9 per riparazioni generiche leggere.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/josam.se\/it\/prodotti\/jh400\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riscaldatore a induzione per lavori leggeri JH400 | JOSAM IT\" \/>\n<meta property=\"og:description\" content=\"JH400 \u00e8 ideale per raddrizzare lamiere e allentare parti piccole come dadi e perni. Utilizzato per lo pi\u00f9 per riparazioni generiche leggere.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/josam.se\/it\/prodotti\/jh400\/\" \/>\n<meta property=\"og:site_name\" content=\"JOSAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/josamsweden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T13:47:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/josam.se\/wp-content\/uploads\/ind-JH400-1920x1152-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/\",\"url\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/\",\"name\":\"Riscaldatore a induzione per lavori leggeri JH400 | JOSAM IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/ind-JH400-1920x1152-1.jpg\",\"datePublished\":\"2024-10-03T20:28:50+00:00\",\"dateModified\":\"2026-06-04T13:47:02+00:00\",\"description\":\"JH400 \u00e8 ideale per raddrizzare lamiere e allentare parti piccole come dadi e perni. Utilizzato per lo pi\u00f9 per riparazioni generiche leggere.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/#primaryimage\",\"url\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/ind-JH400-1920x1152-1.jpg\",\"contentUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/ind-JH400-1920x1152-1.jpg\",\"width\":1920,\"height\":1152,\"caption\":\"JOSAM JH400 induction heater\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/jh400\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/josam.se\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"APPARECCHIATURE DI RISCALDAMENTO A INDUZIONE PER AUTOVEICOLI\",\"item\":\"https:\\\/\\\/josam.se\\\/it\\\/prodotti\\\/riscaldamento-a-induzione\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JH400\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/josam.se\\\/it\\\/\",\"name\":\"JOSAM\",\"description\":\"Heavy Duty\",\"publisher\":{\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/josam.se\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/#organization\",\"name\":\"JOSAM\",\"url\":\"https:\\\/\\\/josam.se\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/JOSAM-NEW-simple-black-cropped.svg\",\"contentUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/JOSAM-NEW-simple-black-cropped.svg\",\"width\":792,\"height\":153,\"caption\":\"JOSAM\"},\"image\":{\"@id\":\"https:\\\/\\\/josam.se\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/josamsweden\",\"https:\\\/\\\/www.instagram.com\\\/josamequipment\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@josamsweden\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/josam\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riscaldatore a induzione per lavori leggeri JH400 | JOSAM IT","description":"JH400 \u00e8 ideale per raddrizzare lamiere e allentare parti piccole come dadi e perni. Utilizzato per lo pi\u00f9 per riparazioni generiche leggere.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/josam.se\/it\/prodotti\/jh400\/","og_locale":"it_IT","og_type":"article","og_title":"Riscaldatore a induzione per lavori leggeri JH400 | JOSAM IT","og_description":"JH400 \u00e8 ideale per raddrizzare lamiere e allentare parti piccole come dadi e perni. Utilizzato per lo pi\u00f9 per riparazioni generiche leggere.","og_url":"https:\/\/josam.se\/it\/prodotti\/jh400\/","og_site_name":"JOSAM","article_publisher":"https:\/\/www.facebook.com\/josamsweden","article_modified_time":"2026-06-04T13:47:02+00:00","og_image":[{"width":1920,"height":1152,"url":"http:\/\/josam.se\/wp-content\/uploads\/ind-JH400-1920x1152-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/josam.se\/it\/prodotti\/jh400\/","url":"https:\/\/josam.se\/it\/prodotti\/jh400\/","name":"Riscaldatore a induzione per lavori leggeri JH400 | JOSAM IT","isPartOf":{"@id":"https:\/\/josam.se\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/josam.se\/it\/prodotti\/jh400\/#primaryimage"},"image":{"@id":"https:\/\/josam.se\/it\/prodotti\/jh400\/#primaryimage"},"thumbnailUrl":"https:\/\/josam.se\/wp-content\/uploads\/ind-JH400-1920x1152-1.jpg","datePublished":"2024-10-03T20:28:50+00:00","dateModified":"2026-06-04T13:47:02+00:00","description":"JH400 \u00e8 ideale per raddrizzare lamiere e allentare parti piccole come dadi e perni. Utilizzato per lo pi\u00f9 per riparazioni generiche leggere.","breadcrumb":{"@id":"https:\/\/josam.se\/it\/prodotti\/jh400\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/josam.se\/it\/prodotti\/jh400\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/josam.se\/it\/prodotti\/jh400\/#primaryimage","url":"https:\/\/josam.se\/wp-content\/uploads\/ind-JH400-1920x1152-1.jpg","contentUrl":"https:\/\/josam.se\/wp-content\/uploads\/ind-JH400-1920x1152-1.jpg","width":1920,"height":1152,"caption":"JOSAM JH400 induction heater"},{"@type":"BreadcrumbList","@id":"https:\/\/josam.se\/it\/prodotti\/jh400\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/josam.se\/it\/"},{"@type":"ListItem","position":2,"name":"APPARECCHIATURE DI RISCALDAMENTO A INDUZIONE PER AUTOVEICOLI","item":"https:\/\/josam.se\/it\/prodotti\/riscaldamento-a-induzione\/"},{"@type":"ListItem","position":3,"name":"JH400"}]},{"@type":"WebSite","@id":"https:\/\/josam.se\/it\/#website","url":"https:\/\/josam.se\/it\/","name":"JOSAM","description":"Heavy Duty","publisher":{"@id":"https:\/\/josam.se\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/josam.se\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/josam.se\/it\/#organization","name":"JOSAM","url":"https:\/\/josam.se\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/josam.se\/it\/#\/schema\/logo\/image\/","url":"https:\/\/josam.se\/wp-content\/uploads\/JOSAM-NEW-simple-black-cropped.svg","contentUrl":"https:\/\/josam.se\/wp-content\/uploads\/JOSAM-NEW-simple-black-cropped.svg","width":792,"height":153,"caption":"JOSAM"},"image":{"@id":"https:\/\/josam.se\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/josamsweden","https:\/\/www.instagram.com\/josamequipment\/","https:\/\/www.youtube.com\/@josamsweden","https:\/\/www.linkedin.com\/company\/josam"]}]}},"_links":{"self":[{"href":"https:\/\/josam.se\/it\/wp-json\/wp\/v2\/product\/2051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josam.se\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/josam.se\/it\/wp-json\/wp\/v2\/types\/product"}],"up":[{"embeddable":true,"href":"https:\/\/josam.se\/it\/wp-json\/wp\/v2\/product\/1657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josam.se\/it\/wp-json\/wp\/v2\/media\/8883"}],"wp:attachment":[{"href":"https:\/\/josam.se\/it\/wp-json\/wp\/v2\/media?parent=2051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}