{"id":1262,"date":"2024-10-03T20:35:46","date_gmt":"2024-10-03T20:35:46","guid":{"rendered":"https:\/\/josam.se\/product\/cam-aligner\/"},"modified":"2026-06-22T16:48:34","modified_gmt":"2026-06-22T16:48:34","slug":"cam-aligner","status":"publish","type":"product","link":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/","title":{"rendered":"Cam-Aligner"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Pr\u00e4zision und Flexibilit\u00e4t f\u00fcr jedes Fahrzeug<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Cam-Aligner von JOSAM ist ein kompaktes und vielseitiges Achsvermessungssystem, das f\u00fcr Werkst\u00e4tten und Reifenservicezentren entwickelt wurde. Es erm\u00f6glicht eine schnelle und genaue Einstellung f\u00fcr eine Vielzahl von Fahrzeugen, von Lkw und Bussen bis hin zu Lieferwagen und Mobilkr\u00e4nen und allem dazwischen. Dank seiner Portabilit\u00e4t kann das System an jedem Ort in der Werkstatt oder sogar beim Kunden vor Ort eingesetzt werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e4zision und Flexibilit\u00e4t f\u00fcr jedes Fahrzeug Der Cam-Aligner von JOSAM ist ein kompaktes und vielseitiges Achsvermessungssystem, das f\u00fcr Werkst\u00e4tten und Reifenservicezentren entwickelt wurde. Es erm\u00f6glicht eine schnelle und genaue Einstellung f\u00fcr eine Vielzahl von Fahrzeugen, von Lkw und Bussen bis hin zu Lieferwagen und Mobilkr\u00e4nen und allem dazwischen. Dank seiner Portabilit\u00e4t kann das System an [&hellip;]<\/p>\n","protected":false},"featured_media":7451,"parent":1642,"menu_order":0,"template":"page-templates\/product-single-cam-aligner.php","format":"standard","meta":[],"class_list":["post-1262","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cam-Aligner | Achsvermessungssystem | JOSAM DE<\/title>\n<meta name=\"description\" content=\"Steigern Sie Ihre Produktivit\u00e4t mit dem Cam-Aligner f\u00fcr eine pr\u00e4zise und effiziente Achsvermessung bei schweren Nutzfahrzeugen, von f\u00fchrenden OEMs empfohlen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/josam.se\/de\/produkte\/cam-aligner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cam-Aligner | Achsvermessungssystem | JOSAM DE\" \/>\n<meta property=\"og:description\" content=\"Steigern Sie Ihre Produktivit\u00e4t mit dem Cam-Aligner f\u00fcr eine pr\u00e4zise und effiziente Achsvermessung bei schweren Nutzfahrzeugen, von f\u00fchrenden OEMs empfohlen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/josam.se\/de\/produkte\/cam-aligner\/\" \/>\n<meta property=\"og:site_name\" content=\"JOSAM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/josamsweden\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T16:48:34+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/josam.se\/wp-content\/uploads\/Cam-Aligner_camera_1920x1152.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/\",\"url\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/\",\"name\":\"Cam-Aligner | Achsvermessungssystem | JOSAM DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/Cam-Aligner_camera_1920x1152.jpg\",\"datePublished\":\"2024-10-03T20:35:46+00:00\",\"dateModified\":\"2026-06-22T16:48:34+00:00\",\"description\":\"Steigern Sie Ihre Produktivit\u00e4t mit dem Cam-Aligner f\u00fcr eine pr\u00e4zise und effiziente Achsvermessung bei schweren Nutzfahrzeugen, von f\u00fchrenden OEMs empfohlen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/Cam-Aligner_camera_1920x1152.jpg\",\"contentUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/Cam-Aligner_camera_1920x1152.jpg\",\"width\":1920,\"height\":1152,\"caption\":\"Cam-Aligner wheel aligner\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/produkte\\\/cam-aligner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/josam.se\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HOCHLEISTUNGSAUSR\u00dcSTUNG ZUR ACHSVERMESSUNG\",\"item\":\"http:\\\/\\\/josam.se\\\/de\\\/produkte\\\/achsvermessung\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cam-Aligner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/josam.se\\\/de\\\/\",\"name\":\"JOSAM\",\"description\":\"Heavy Duty\",\"publisher\":{\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/josam.se\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/#organization\",\"name\":\"JOSAM\",\"url\":\"https:\\\/\\\/josam.se\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/JOSAM-NEW-simple-black-cropped.svg\",\"contentUrl\":\"https:\\\/\\\/josam.se\\\/wp-content\\\/uploads\\\/JOSAM-NEW-simple-black-cropped.svg\",\"width\":792,\"height\":153,\"caption\":\"JOSAM\"},\"image\":{\"@id\":\"https:\\\/\\\/josam.se\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/josamsweden\",\"https:\\\/\\\/www.instagram.com\\\/josamequipment\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@josamsweden\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/josam\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cam-Aligner | Achsvermessungssystem | JOSAM DE","description":"Steigern Sie Ihre Produktivit\u00e4t mit dem Cam-Aligner f\u00fcr eine pr\u00e4zise und effiziente Achsvermessung bei schweren Nutzfahrzeugen, von f\u00fchrenden OEMs empfohlen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/","og_locale":"de_DE","og_type":"article","og_title":"Cam-Aligner | Achsvermessungssystem | JOSAM DE","og_description":"Steigern Sie Ihre Produktivit\u00e4t mit dem Cam-Aligner f\u00fcr eine pr\u00e4zise und effiziente Achsvermessung bei schweren Nutzfahrzeugen, von f\u00fchrenden OEMs empfohlen.","og_url":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/","og_site_name":"JOSAM","article_publisher":"https:\/\/www.facebook.com\/josamsweden","article_modified_time":"2026-06-22T16:48:34+00:00","og_image":[{"width":1920,"height":1152,"url":"http:\/\/josam.se\/wp-content\/uploads\/Cam-Aligner_camera_1920x1152.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/","url":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/","name":"Cam-Aligner | Achsvermessungssystem | JOSAM DE","isPartOf":{"@id":"https:\/\/josam.se\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/#primaryimage"},"image":{"@id":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/#primaryimage"},"thumbnailUrl":"https:\/\/josam.se\/wp-content\/uploads\/Cam-Aligner_camera_1920x1152.jpg","datePublished":"2024-10-03T20:35:46+00:00","dateModified":"2026-06-22T16:48:34+00:00","description":"Steigern Sie Ihre Produktivit\u00e4t mit dem Cam-Aligner f\u00fcr eine pr\u00e4zise und effiziente Achsvermessung bei schweren Nutzfahrzeugen, von f\u00fchrenden OEMs empfohlen.","breadcrumb":{"@id":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/josam.se\/de\/produkte\/cam-aligner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/#primaryimage","url":"https:\/\/josam.se\/wp-content\/uploads\/Cam-Aligner_camera_1920x1152.jpg","contentUrl":"https:\/\/josam.se\/wp-content\/uploads\/Cam-Aligner_camera_1920x1152.jpg","width":1920,"height":1152,"caption":"Cam-Aligner wheel aligner"},{"@type":"BreadcrumbList","@id":"https:\/\/josam.se\/de\/produkte\/cam-aligner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/josam.se\/de\/"},{"@type":"ListItem","position":2,"name":"HOCHLEISTUNGSAUSR\u00dcSTUNG ZUR ACHSVERMESSUNG","item":"http:\/\/josam.se\/de\/produkte\/achsvermessung\/"},{"@type":"ListItem","position":3,"name":"Cam-Aligner"}]},{"@type":"WebSite","@id":"https:\/\/josam.se\/de\/#website","url":"https:\/\/josam.se\/de\/","name":"JOSAM","description":"Heavy Duty","publisher":{"@id":"https:\/\/josam.se\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/josam.se\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/josam.se\/de\/#organization","name":"JOSAM","url":"https:\/\/josam.se\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/josam.se\/de\/#\/schema\/logo\/image\/","url":"https:\/\/josam.se\/wp-content\/uploads\/JOSAM-NEW-simple-black-cropped.svg","contentUrl":"https:\/\/josam.se\/wp-content\/uploads\/JOSAM-NEW-simple-black-cropped.svg","width":792,"height":153,"caption":"JOSAM"},"image":{"@id":"https:\/\/josam.se\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/josamsweden","https:\/\/www.instagram.com\/josamequipment\/","https:\/\/www.youtube.com\/@josamsweden","https:\/\/www.linkedin.com\/company\/josam"]}]}},"_links":{"self":[{"href":"https:\/\/josam.se\/de\/wp-json\/wp\/v2\/product\/1262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/josam.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/josam.se\/de\/wp-json\/wp\/v2\/types\/product"}],"up":[{"embeddable":true,"href":"https:\/\/josam.se\/de\/wp-json\/wp\/v2\/product\/1642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/josam.se\/de\/wp-json\/wp\/v2\/media\/7451"}],"wp:attachment":[{"href":"https:\/\/josam.se\/de\/wp-json\/wp\/v2\/media?parent=1262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}